{"id":2043,"date":"2021-08-03T16:06:59","date_gmt":"2021-08-03T08:06:59","guid":{"rendered":"https:\/\/www.healinghands.com.hk\/video-category\/"},"modified":"2024-06-21T11:15:22","modified_gmt":"2024-06-21T03:15:22","slug":"video-category","status":"publish","type":"page","link":"https:\/\/www.healinghands.com.hk\/en\/video-category\/","title":{"rendered":"Health Education"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2043\" class=\"elementor elementor-2043\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff889f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff889f6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7eec1a3\" data-id=\"7eec1a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4e4e4e elementor-widget elementor-widget-text-editor\" data-id=\"f4e4e4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Our clinic would provide physiotherapy-related health seminar among different organizations. Co-operated organizations included:<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf7639 elementor-hidden-desktop elementor-hidden-tablet elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"5cf7639\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;8&quot;,&quot;slides_to_show_mobile&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;8&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/546554654.jpg\" alt=\"546554654\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/564654.jpg\" alt=\"564654\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6546546.jpg\" alt=\"6546546\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435435.jpg\" alt=\"5435435435\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435452.jpg\" alt=\"5435435452\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/54354543.png\" alt=\"54354543\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6435435435.jpg\" alt=\"6435435435\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/543543543.jpg\" alt=\"543543543\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3543543534.jpg\" alt=\"3543543534\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5354354.jpg\" alt=\"5354354\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5646546.jpg\" alt=\"5646546\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321321321-300x164.jpg\" alt=\"21321321321\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/35343421321-300x164.jpg\" alt=\"35343421321\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/323122141.jpg\" alt=\"323122141\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21312312.jpg\" alt=\"21312312\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/432432423.jpg\" alt=\"432432423\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/2321321.jpg\" alt=\"2321321\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/412321321.jpg\" alt=\"412321321\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/42121321.jpg\" alt=\"42121321\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3213213.jpg\" alt=\"3213213\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41421321-300x164.jpg\" alt=\"41421321\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/414232.jpg\" alt=\"414232\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/4332132.jpg\" alt=\"4332132\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41321321.jpg\" alt=\"41321321\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/14214214213.jpg\" alt=\"14214214213\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321312.jpg\" alt=\"21321312\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa56614 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa56614\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-413b8a4\" data-id=\"413b8a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec955b elementor-hidden-phone elementor-widget elementor-widget-image-gallery\" data-id=\"eec955b\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 11%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2043 gallery-columns-9 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/543543543.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/543543543.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/543543543-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"164\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41421321-300x164.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41421321-300x164.jpg 300w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41421321-90x49.jpg 90w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41421321-250x136.jpg 250w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41421321-768x419.jpg 768w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41421321.jpg 917w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/4332132.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/4332132.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/4332132-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41321321.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41321321.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/41321321-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/323122141.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/323122141.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/323122141-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/414232.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/414232.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/414232-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/2321321.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/2321321.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/2321321-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3543543534.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3543543534.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3543543534-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321312.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321312.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321312-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/564654.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/564654.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/564654-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6546546.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6546546.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6546546-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435452.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435452.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435452-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3213213.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3213213.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/3213213-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/412321321.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/412321321.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/412321321-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6435435435.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6435435435.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/6435435435-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"164\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321321321-300x164.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321321321-300x164.jpg 300w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321321321-90x49.jpg 90w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321321321-250x136.jpg 250w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321321321-768x419.jpg 768w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21321321321.jpg 917w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/54354543.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/54354543.png 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/54354543-90x49.png 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/42121321.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/42121321.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/42121321-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21312312.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21312312.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/21312312-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/14214214213.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/14214214213.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/14214214213-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5646546.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5646546.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5646546-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/432432423.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/432432423.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/432432423-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"164\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/35343421321-300x164.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/35343421321-300x164.jpg 300w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/35343421321-90x49.jpg 90w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/35343421321-250x136.jpg 250w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/35343421321-768x419.jpg 768w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/35343421321.jpg 917w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/546554654.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/546554654.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/546554654-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435435.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435435.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5435435435-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"120\" src=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5354354.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5354354.jpg 220w, https:\/\/www.healinghands.com.hk\/wp-content\/uploads\/2021\/08\/5354354-90x49.jpg 90w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-705811d elementor-widget elementor-widget-spacer\" data-id=\"705811d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5d2f18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5d2f18\" data-element_type=\"section\" data-settings=\"{&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-709a9cf\" data-id=\"709a9cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f466000 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f466000\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.healinghands.com.hk\/en\/video-category\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">TV &amp; Radio<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-11bbe9f\" data-id=\"11bbe9f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b014aa0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b014aa0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.healinghands.com.hk\/en\/%e5%a0%b1%e7%ab%a0%e9%9b%9c%e8%aa%8c\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Newspaper &amp; Magazine<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1c17864\" data-id=\"1c17864\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-368f2b5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"368f2b5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.healinghands.com.hk\/en\/%e6%b4%bb%e5%8b%95%e5%9b%9e%e9%a1%a7\/\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Activity Review<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-299bbd9\" data-id=\"299bbd9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-adea943 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"adea943\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77bde2d\" data-id=\"77bde2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9096627 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-global elementor-global-5972 elementor-widget-social-icons\" data-id=\"9096627\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-4dcb281\" href=\"http:\/\/facebook.com\/hhphysio\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-cf313bc\" href=\"https:\/\/www.youtube.com\/c\/healinghandstv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-9e238fc\" href=\"https:\/\/www.instagram.com\/hhphysio\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3286189 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3286189\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6110084\" data-id=\"6110084\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c83c43 elementor-widget elementor-widget-html\" data-id=\"3c83c43\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script src=\"https:\/\/static.elfsight.com\/platform\/platform.js\" data-use-service-core defer><\/script>\r\n<div class=\"elfsight-app-92d8de1d-0028-4a8f-857d-61620184fcf3\" data-elfsight-app-lazy><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82064d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82064d1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6841917\" data-id=\"6841917\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u672c\u4e2d\u5fc3\u53ef\u70ba\u5404\u5927\u6a5f\u69cb\u63d0\u4f9b\u7269\u7406\u6cbb\u7642\u76f8\u95dc\u5065\u5eb7\u8b1b\u5ea7\u6216\u7814\u8a0e\u6703\u3002\u66fe\u5408\u4f5c\u5925\u4f34\u5305\u62ec\uff1a \u96fb\u8996\u96fb\u53f0\u200b \u5831\u7ae0\u96dc\u8a8c \u6d3b\u52d5\u56de\u9867 Face<\/p>\n<div class=\"klb-readmore\"><a class=\"c-btn\" href=\"https:\/\/www.healinghands.com.hk\/en\/video-category\/\">Read More <i class=\"far fa-plus\"><\/i><\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-2043","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/pages\/2043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/comments?post=2043"}],"version-history":[{"count":118,"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/pages\/2043\/revisions"}],"predecessor-version":[{"id":6834,"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/pages\/2043\/revisions\/6834"}],"wp:attachment":[{"href":"https:\/\/www.healinghands.com.hk\/en\/wp-json\/wp\/v2\/media?parent=2043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}